{"id":4237,"count":1,"description":"","link":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/tag\/astros\/","name":"astros","slug":"astros","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/tags\/4237"}],"collection":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/posts?tags=4237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}