{"id":18812,"count":1,"description":"","link":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/tag\/prime\/","name":"PRIME","slug":"prime","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/tags\/18812"}],"collection":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/posts?tags=18812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}