{"id":12978,"count":1,"description":"","link":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/tag\/hesed\/","name":"hesed","slug":"hesed","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/tags\/12978"}],"collection":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/posts?tags=12978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}