{"id":9013,"date":"2025-12-30T14:00:26","date_gmt":"2025-12-30T17:00:26","guid":{"rendered":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/2025\/12\/30\/5-dicas-para-engajar-a-equipe-em-tempos-incertos\/"},"modified":"2025-12-30T14:00:26","modified_gmt":"2025-12-30T17:00:26","slug":"5-dicas-para-engajar-a-equipe-em-tempos-incertos","status":"publish","type":"post","link":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/2025\/12\/30\/5-dicas-para-engajar-a-equipe-em-tempos-incertos\/","title":{"rendered":"5 dicas para engajar a equipe em tempos incertos"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"580\" height=\"385\" src=\"https:\/\/www.youtube.com\/embed\/vHEt8wvuCbI?modestbranding=1\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\n<br \/>Sua equipe est\u00e1 desmotivada? Existe um cen\u00e1rio incerto pra voc\u00eas? Conhe\u00e7a essas 5 <a href=\"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/2019\/11\/14\/dicas-do-linkedin-sobre-o-uso-da-plataforma-na-area-da-saude\/\" data-seo-automated-link-building=\"3\" title=\"Dicas do LinkedIn sobre o uso da plataforma na \u00e1rea da sa\u00fade\">dicas<\/a> para voc\u00ea engajar o time!<br \/>\nCurta e siga o canal  <img src=\"data:image\/gif;base64,R0lGODdhAQABAPAAAP\/\/\/wAAACwAAAAAAQABAEACAkQBADs=\" data-lazy-src=\"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-includes\/images\/smilies\/\ud83d\ude00\" alt=\":D\" class=\"wp-smiley\" \/> <br \/>\n&#8212;<br \/>\nFerramenta para descontrair e brincar com a equipe de forma remota:<br \/>\nGartic:<br \/>\n&#8212;<\/p>\n<p>\ud83d\udc1f Fa\u00e7a parte do Clube da Agilidade:<br \/>\n\ud83d\udcf0  Acesse nosso blog:<br \/>\n\ud83c\udf05  Instagram:<br \/>\n\ud83d\udcbb  LinkedIn:<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sua equipe est\u00e1 desmotivada? Existe um cen\u00e1rio incerto pra voc\u00eas? Conhe\u00e7a essas 5 dicas para voc\u00ea engajar o time! Curta e siga o canal &#8212; Ferramenta para descontrair e brincar com a equipe de forma remota: Gartic: &#8212; \ud83d\udc1f Fa\u00e7a parte do Clube da Agilidade: \ud83d\udcf0 Acesse nosso blog: \ud83c\udf05 Instagram: \ud83d\udcbb LinkedIn:<\/p>\n","protected":false},"author":1,"featured_media":9014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[2],"tags":[2241,15,1047,19660,3100,19661,1045,5109],"_links":{"self":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/posts\/9013"}],"collection":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/comments?post=9013"}],"version-history":[{"count":0,"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/posts\/9013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/media\/9014"}],"wp:attachment":[{"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/media?parent=9013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/categories?post=9013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicasempregos.cidadesbr.net.br\/vagas\/wp-json\/wp\/v2\/tags?post=9013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}